{"id":783,"date":"2008-04-05T19:56:00","date_gmt":"2008-04-05T19:56:00","guid":{"rendered":"http:\/\/wp.andreas.bieri.name\/myblog\/?p=783"},"modified":"2008-04-05T19:56:00","modified_gmt":"2008-04-05T19:56:00","slug":"workshop-virtualisierung-mit-vmware-server","status":"publish","type":"post","link":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/2008\/04\/05\/workshop-virtualisierung-mit-vmware-server\/","title":{"rendered":"Workshop Virtualisierung mit Vmware Server"},"content":{"rendered":"<p>Im April 2008 habe ich einen mehrteiligen Workshop zum Thema Virtualisierung durchgef\u00fchrt. Nach einer einf\u00fchrenden Pr\u00e4sentation mit einer Markt\u00fcbersicht damals aktueller Virtualisierungs-Software wurden in drei praktischen Teilen die Virtualisierung mit Vmware Server vorgestellt und durchgef\u00fchrt.<\/p>\n<p>Hier ist die <a href=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/05\/Was_ist_Virtualisierung.pdf\" rel=\"\">Pr\u00e4sentation<\/a> im PDF Format<\/p>\n<p>Die Unterlagen der praktischen Teile sind hier:<\/p>\n<p><a href=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/05\/Modul_A.pdf\" rel=\"\">Modul_A<\/a>: Arbeiten mit fertigen virtuellen Maschinen<br \/>\n<a href=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/05\/Modul_B.pdf\" rel=\"\">Modul_B<\/a>: Erstellen und Einrichten von virtuellen Maschinen<br \/>\n<a href=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/05\/Modul_C.pdf\" rel=\"\">Modul_C<\/a>: Umwandlung von realen PCs in eine virtuelle Maschine (Ausblick)<\/p>\n<p>Die Unterlagen wurden mit LaTeX und der Beamer Klasse resp. mit den Paketen longtable, hyperref und einigen anderen erstellt. Bei den langen Tabellen mit Bildern konnte LaTeX seine St\u00e4rken ausspielen: alle Bilder werden automatisch von der Festplatte geholt und eingebunden, wobei alle Bilder auf eine einheitliche Breite angepasst werden. Details sind <a href=\"http:\/\/wp.andreas.bieri.name\/myblog\/index.php\/2008\/04\/05\/technische-dokumentationen-mit-latex\/\">hier<\/a> nachzulesen.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im April 2008 habe ich einen mehrteiligen Workshop zum Thema Virtualisierung durchgef\u00fchrt. Nach einer einf\u00fchrenden Pr\u00e4sentation mit einer Markt\u00fcbersicht damals aktueller Virtualisierungs-Software wurden in drei praktischen Teilen die Virtualisierung mit Vmware Server vorgestellt und durchgef\u00fchrt. Hier ist die Pr\u00e4sentation im PDF Format Die Unterlagen der praktischen Teile sind hier: Modul_A: Arbeiten mit fertigen virtuellen Maschinen [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[70,141],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Workshop Virtualisierung mit Vmware Server - Merkbar.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/wp.andreas.bieri.name\/myblog\/2008\/04\/05\/workshop-virtualisierung-mit-vmware-server\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Workshop Virtualisierung mit Vmware Server - Merkbar.\" \/>\n<meta property=\"og:description\" content=\"Im April 2008 habe ich einen mehrteiligen Workshop zum Thema Virtualisierung durchgef\u00fchrt. Nach einer einf\u00fchrenden Pr\u00e4sentation mit einer Markt\u00fcbersicht damals aktueller Virtualisierungs-Software wurden in drei praktischen Teilen die Virtualisierung mit Vmware Server vorgestellt und durchgef\u00fchrt. Hier ist die Pr\u00e4sentation im PDF Format Die Unterlagen der praktischen Teile sind hier: Modul_A: Arbeiten mit fertigen virtuellen Maschinen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/wp.andreas.bieri.name\/myblog\/2008\/04\/05\/workshop-virtualisierung-mit-vmware-server\/\" \/>\n<meta property=\"og:site_name\" content=\"Merkbar.\" \/>\n<meta property=\"article:published_time\" content=\"2008-04-05T19:56:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"wp_blogadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#website\",\"url\":\"https:\/\/wp.andreas.bieri.name\/myblog\/\",\"name\":\"Merkbar.\",\"description\":\"IT, Elektronik und Mathematik\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wp.andreas.bieri.name\/myblog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/wp.andreas.bieri.name\/myblog\/2008\/04\/05\/workshop-virtualisierung-mit-vmware-server\/#webpage\",\"url\":\"http:\/\/wp.andreas.bieri.name\/myblog\/2008\/04\/05\/workshop-virtualisierung-mit-vmware-server\/\",\"name\":\"Workshop Virtualisierung mit Vmware Server - Merkbar.\",\"isPartOf\":{\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#website\"},\"datePublished\":\"2008-04-05T19:56:00+00:00\",\"dateModified\":\"2008-04-05T19:56:00+00:00\",\"author\":{\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#\/schema\/person\/47691942dec3f2eb9d34bb8b5507870d\"},\"breadcrumb\":{\"@id\":\"http:\/\/wp.andreas.bieri.name\/myblog\/2008\/04\/05\/workshop-virtualisierung-mit-vmware-server\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/wp.andreas.bieri.name\/myblog\/2008\/04\/05\/workshop-virtualisierung-mit-vmware-server\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/wp.andreas.bieri.name\/myblog\/2008\/04\/05\/workshop-virtualisierung-mit-vmware-server\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/wp.andreas.bieri.name\/myblog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Workshop Virtualisierung mit Vmware Server\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#\/schema\/person\/47691942dec3f2eb9d34bb8b5507870d\",\"name\":\"wp_blogadmin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#personlogo\",\"inLanguage\":\"de\",\"url\":\"http:\/\/1.gravatar.com\/avatar\/d0dc804558b03f640b22e497ec010c9a?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/1.gravatar.com\/avatar\/d0dc804558b03f640b22e497ec010c9a?s=96&d=mm&r=g\",\"caption\":\"wp_blogadmin\"},\"url\":\"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/author\/wp_blogadmin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Workshop Virtualisierung mit Vmware Server - Merkbar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/wp.andreas.bieri.name\/myblog\/2008\/04\/05\/workshop-virtualisierung-mit-vmware-server\/","og_locale":"de_DE","og_type":"article","og_title":"Workshop Virtualisierung mit Vmware Server - Merkbar.","og_description":"Im April 2008 habe ich einen mehrteiligen Workshop zum Thema Virtualisierung durchgef\u00fchrt. Nach einer einf\u00fchrenden Pr\u00e4sentation mit einer Markt\u00fcbersicht damals aktueller Virtualisierungs-Software wurden in drei praktischen Teilen die Virtualisierung mit Vmware Server vorgestellt und durchgef\u00fchrt. Hier ist die Pr\u00e4sentation im PDF Format Die Unterlagen der praktischen Teile sind hier: Modul_A: Arbeiten mit fertigen virtuellen Maschinen [&hellip;]","og_url":"http:\/\/wp.andreas.bieri.name\/myblog\/2008\/04\/05\/workshop-virtualisierung-mit-vmware-server\/","og_site_name":"Merkbar.","article_published_time":"2008-04-05T19:56:00+00:00","twitter_card":"summary","twitter_misc":{"Verfasst von":"wp_blogadmin","Gesch\u00e4tzte Lesezeit":"1 Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#website","url":"https:\/\/wp.andreas.bieri.name\/myblog\/","name":"Merkbar.","description":"IT, Elektronik und Mathematik","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wp.andreas.bieri.name\/myblog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"WebPage","@id":"http:\/\/wp.andreas.bieri.name\/myblog\/2008\/04\/05\/workshop-virtualisierung-mit-vmware-server\/#webpage","url":"http:\/\/wp.andreas.bieri.name\/myblog\/2008\/04\/05\/workshop-virtualisierung-mit-vmware-server\/","name":"Workshop Virtualisierung mit Vmware Server - Merkbar.","isPartOf":{"@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#website"},"datePublished":"2008-04-05T19:56:00+00:00","dateModified":"2008-04-05T19:56:00+00:00","author":{"@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#\/schema\/person\/47691942dec3f2eb9d34bb8b5507870d"},"breadcrumb":{"@id":"http:\/\/wp.andreas.bieri.name\/myblog\/2008\/04\/05\/workshop-virtualisierung-mit-vmware-server\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/wp.andreas.bieri.name\/myblog\/2008\/04\/05\/workshop-virtualisierung-mit-vmware-server\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/wp.andreas.bieri.name\/myblog\/2008\/04\/05\/workshop-virtualisierung-mit-vmware-server\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/wp.andreas.bieri.name\/myblog\/"},{"@type":"ListItem","position":2,"name":"Workshop Virtualisierung mit Vmware Server"}]},{"@type":"Person","@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#\/schema\/person\/47691942dec3f2eb9d34bb8b5507870d","name":"wp_blogadmin","image":{"@type":"ImageObject","@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#personlogo","inLanguage":"de","url":"http:\/\/1.gravatar.com\/avatar\/d0dc804558b03f640b22e497ec010c9a?s=96&d=mm&r=g","contentUrl":"http:\/\/1.gravatar.com\/avatar\/d0dc804558b03f640b22e497ec010c9a?s=96&d=mm&r=g","caption":"wp_blogadmin"},"url":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/author\/wp_blogadmin\/"}]}},"_links":{"self":[{"href":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-json\/wp\/v2\/posts\/783"}],"collection":[{"href":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-json\/wp\/v2\/comments?post=783"}],"version-history":[{"count":0,"href":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-json\/wp\/v2\/posts\/783\/revisions"}],"wp:attachment":[{"href":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-json\/wp\/v2\/media?parent=783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-json\/wp\/v2\/categories?post=783"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-json\/wp\/v2\/tags?post=783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}