{"id":3991,"date":"2024-10-31T19:25:42","date_gmt":"2024-10-31T18:25:42","guid":{"rendered":"http:\/\/wp.andreas.bieri.name\/myblog\/?p=3991"},"modified":"2024-10-29T19:36:01","modified_gmt":"2024-10-29T18:36:01","slug":"die-dritte-und-vierte-hand","status":"publish","type":"post","link":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/2024\/10\/31\/die-dritte-und-vierte-hand\/","title":{"rendered":"Die dritte (und vierte) Hand"},"content":{"rendered":"<p>Es ist doch immer schwierig, bei den heutigen kleinen elektronischen Bauelementen Messungen vorzunehmen. Schon das L\u00f6ten ist eine fummelige Angelegenheit. Die billigen kleine dritten H\u00e4nde mit Krokodilklemmen nerven mehr als sie helfen. Vor kurzem habe ich ein System entdeckt, das die Platinen mit magnetischen Pfosten festh\u00e4lt.<\/p>\n<p><img loading=\"lazy\" class=\"aligncenter\" src=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2024\/10\/pcbite2.jpg\" width=\"600\" height=\"474\" \/><\/p>\n<p>Nat\u00fcrlich lassen sich damit nicht alle Teile einspannen, aber f\u00fcr kleine Platinen bew\u00e4hrt es sich schon mal gut beim Messen. Mit dem dazu erh\u00e4ltlichen Messspitzen (einfache Drahtspitzen und Oszilloskop-Tastk\u00f6pfe) lassen sich zuverl\u00e4sssig Signale zum Messen abgreifen. Die Leitungen werden an einen magnetischen Schwanenhals mittels Gummiringen angeschnallt. Durch das Eigengewicht dr\u00fccken die gefederten Spitzen auf die Kontakte.<\/p>\n<p><img loading=\"lazy\" class=\"wp-image-3996 aligncenter\" src=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2024\/10\/pcbite4.jpg\" alt=\"\" width=\"599\" height=\"449\" srcset=\"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-content\/uploads\/2024\/10\/pcbite4.jpg 977w, http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-content\/uploads\/2024\/10\/pcbite4-300x225.jpg 300w, http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-content\/uploads\/2024\/10\/pcbite4-768x575.jpg 768w, http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-content\/uploads\/2024\/10\/pcbite4-830x622.jpg 830w, http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-content\/uploads\/2024\/10\/pcbite4-230x172.jpg 230w, http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-content\/uploads\/2024\/10\/pcbite4-350x262.jpg 350w, http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-content\/uploads\/2024\/10\/pcbite4-480x360.jpg 480w\" sizes=\"(max-width: 599px) 100vw, 599px\" \/><\/p>\n<p>Die Lupe ist angenehm zu benutzen und gross genug. Es gibt kaum Verzerrungen zum Rand hin.<\/p>\n<p><img loading=\"lazy\" class=\"wp-image-3993 aligncenter\" src=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2024\/10\/pcbite1.jpg\" alt=\"\" width=\"600\" height=\"446\" srcset=\"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-content\/uploads\/2024\/10\/pcbite1.jpg 906w, http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-content\/uploads\/2024\/10\/pcbite1-300x223.jpg 300w, http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-content\/uploads\/2024\/10\/pcbite1-768x570.jpg 768w, http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-content\/uploads\/2024\/10\/pcbite1-830x617.jpg 830w, http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-content\/uploads\/2024\/10\/pcbite1-230x171.jpg 230w, http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-content\/uploads\/2024\/10\/pcbite1-350x260.jpg 350w, http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-content\/uploads\/2024\/10\/pcbite1-480x357.jpg 480w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es ist doch immer schwierig, bei den heutigen kleinen elektronischen Bauelementen Messungen vorzunehmen. Schon das L\u00f6ten ist eine fummelige Angelegenheit. Die billigen kleine dritten H\u00e4nde mit Krokodilklemmen nerven mehr als sie helfen. Vor kurzem habe ich ein System entdeckt, das die Platinen mit magnetischen Pfosten festh\u00e4lt. Nat\u00fcrlich lassen sich damit nicht alle Teile einspannen, aber [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Die dritte (und vierte) Hand - Merkbar.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/52.29.166.97\/myblog\/2024\/10\/31\/die-dritte-und-vierte-hand\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die dritte (und vierte) Hand - Merkbar.\" \/>\n<meta property=\"og:description\" content=\"Es ist doch immer schwierig, bei den heutigen kleinen elektronischen Bauelementen Messungen vorzunehmen. Schon das L\u00f6ten ist eine fummelige Angelegenheit. Die billigen kleine dritten H\u00e4nde mit Krokodilklemmen nerven mehr als sie helfen. Vor kurzem habe ich ein System entdeckt, das die Platinen mit magnetischen Pfosten festh\u00e4lt. Nat\u00fcrlich lassen sich damit nicht alle Teile einspannen, aber [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/52.29.166.97\/myblog\/2024\/10\/31\/die-dritte-und-vierte-hand\/\" \/>\n<meta property=\"og:site_name\" content=\"Merkbar.\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-31T18:25:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-29T18:36:01+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2024\/10\/pcbite2.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"wp_blogadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#website\",\"url\":\"https:\/\/wp.andreas.bieri.name\/myblog\/\",\"name\":\"Merkbar.\",\"description\":\"IT, Elektronik und Mathematik\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wp.andreas.bieri.name\/myblog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/52.29.166.97\/myblog\/2024\/10\/31\/die-dritte-und-vierte-hand\/#primaryimage\",\"inLanguage\":\"de\",\"url\":\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2024\/10\/pcbite2.jpg\",\"contentUrl\":\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2024\/10\/pcbite2.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/52.29.166.97\/myblog\/2024\/10\/31\/die-dritte-und-vierte-hand\/#webpage\",\"url\":\"http:\/\/52.29.166.97\/myblog\/2024\/10\/31\/die-dritte-und-vierte-hand\/\",\"name\":\"Die dritte (und vierte) Hand - Merkbar.\",\"isPartOf\":{\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/52.29.166.97\/myblog\/2024\/10\/31\/die-dritte-und-vierte-hand\/#primaryimage\"},\"datePublished\":\"2024-10-31T18:25:42+00:00\",\"dateModified\":\"2024-10-29T18:36:01+00:00\",\"author\":{\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#\/schema\/person\/47691942dec3f2eb9d34bb8b5507870d\"},\"breadcrumb\":{\"@id\":\"http:\/\/52.29.166.97\/myblog\/2024\/10\/31\/die-dritte-und-vierte-hand\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/52.29.166.97\/myblog\/2024\/10\/31\/die-dritte-und-vierte-hand\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/52.29.166.97\/myblog\/2024\/10\/31\/die-dritte-und-vierte-hand\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/wp.andreas.bieri.name\/myblog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die dritte (und vierte) Hand\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#\/schema\/person\/47691942dec3f2eb9d34bb8b5507870d\",\"name\":\"wp_blogadmin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#personlogo\",\"inLanguage\":\"de\",\"url\":\"http:\/\/1.gravatar.com\/avatar\/d0dc804558b03f640b22e497ec010c9a?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/1.gravatar.com\/avatar\/d0dc804558b03f640b22e497ec010c9a?s=96&d=mm&r=g\",\"caption\":\"wp_blogadmin\"},\"url\":\"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/author\/wp_blogadmin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die dritte (und vierte) Hand - Merkbar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/52.29.166.97\/myblog\/2024\/10\/31\/die-dritte-und-vierte-hand\/","og_locale":"de_DE","og_type":"article","og_title":"Die dritte (und vierte) Hand - Merkbar.","og_description":"Es ist doch immer schwierig, bei den heutigen kleinen elektronischen Bauelementen Messungen vorzunehmen. Schon das L\u00f6ten ist eine fummelige Angelegenheit. Die billigen kleine dritten H\u00e4nde mit Krokodilklemmen nerven mehr als sie helfen. Vor kurzem habe ich ein System entdeckt, das die Platinen mit magnetischen Pfosten festh\u00e4lt. Nat\u00fcrlich lassen sich damit nicht alle Teile einspannen, aber [&hellip;]","og_url":"http:\/\/52.29.166.97\/myblog\/2024\/10\/31\/die-dritte-und-vierte-hand\/","og_site_name":"Merkbar.","article_published_time":"2024-10-31T18:25:42+00:00","article_modified_time":"2024-10-29T18:36:01+00:00","og_image":[{"url":"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2024\/10\/pcbite2.jpg"}],"twitter_card":"summary","twitter_misc":{"Verfasst von":"wp_blogadmin","Gesch\u00e4tzte Lesezeit":"1 Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#website","url":"https:\/\/wp.andreas.bieri.name\/myblog\/","name":"Merkbar.","description":"IT, Elektronik und Mathematik","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wp.andreas.bieri.name\/myblog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","@id":"http:\/\/52.29.166.97\/myblog\/2024\/10\/31\/die-dritte-und-vierte-hand\/#primaryimage","inLanguage":"de","url":"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2024\/10\/pcbite2.jpg","contentUrl":"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2024\/10\/pcbite2.jpg"},{"@type":"WebPage","@id":"http:\/\/52.29.166.97\/myblog\/2024\/10\/31\/die-dritte-und-vierte-hand\/#webpage","url":"http:\/\/52.29.166.97\/myblog\/2024\/10\/31\/die-dritte-und-vierte-hand\/","name":"Die dritte (und vierte) Hand - Merkbar.","isPartOf":{"@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/52.29.166.97\/myblog\/2024\/10\/31\/die-dritte-und-vierte-hand\/#primaryimage"},"datePublished":"2024-10-31T18:25:42+00:00","dateModified":"2024-10-29T18:36:01+00:00","author":{"@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#\/schema\/person\/47691942dec3f2eb9d34bb8b5507870d"},"breadcrumb":{"@id":"http:\/\/52.29.166.97\/myblog\/2024\/10\/31\/die-dritte-und-vierte-hand\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/52.29.166.97\/myblog\/2024\/10\/31\/die-dritte-und-vierte-hand\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/52.29.166.97\/myblog\/2024\/10\/31\/die-dritte-und-vierte-hand\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/wp.andreas.bieri.name\/myblog\/"},{"@type":"ListItem","position":2,"name":"Die dritte (und vierte) Hand"}]},{"@type":"Person","@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#\/schema\/person\/47691942dec3f2eb9d34bb8b5507870d","name":"wp_blogadmin","image":{"@type":"ImageObject","@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#personlogo","inLanguage":"de","url":"http:\/\/1.gravatar.com\/avatar\/d0dc804558b03f640b22e497ec010c9a?s=96&d=mm&r=g","contentUrl":"http:\/\/1.gravatar.com\/avatar\/d0dc804558b03f640b22e497ec010c9a?s=96&d=mm&r=g","caption":"wp_blogadmin"},"url":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/author\/wp_blogadmin\/"}]}},"_links":{"self":[{"href":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-json\/wp\/v2\/posts\/3991"}],"collection":[{"href":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-json\/wp\/v2\/comments?post=3991"}],"version-history":[{"count":7,"href":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-json\/wp\/v2\/posts\/3991\/revisions"}],"predecessor-version":[{"id":4002,"href":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-json\/wp\/v2\/posts\/3991\/revisions\/4002"}],"wp:attachment":[{"href":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-json\/wp\/v2\/media?parent=3991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-json\/wp\/v2\/categories?post=3991"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-json\/wp\/v2\/tags?post=3991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}