{"id":2356,"date":"2017-01-22T09:28:02","date_gmt":"2017-01-22T09:28:02","guid":{"rendered":"http:\/\/wp.andreas.bieri.name\/myblog\/?p=2356"},"modified":"2017-01-22T09:28:02","modified_gmt":"2017-01-22T09:28:02","slug":"raspberry-pi-sichern-sd-card-schrumpfen","status":"publish","type":"post","link":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/2017\/01\/22\/raspberry-pi-sichern-sd-card-schrumpfen\/","title":{"rendered":"Raspberry Pi sichern, SD Card schrumpfen"},"content":{"rendered":"<p>Die neueren Raspberry Pi Betriebssystem sind mittlerweile recht tolerant gegen\u00fcber &#8222;Stromausf\u00e4llen&#8220; geworden. Meine beiden RPi V3 mit Raspbian Jessie (Lite) haben\u00a0schon Dutzende\u00a0provizierte &#8222;Abst\u00fcrze&#8220; \u00fcberlebt. Trotzdem muss man ab und zu eine Sicherung anlagen. Daraus mache ich keine grosse Sache:<\/p>\n<ul>\n<li>Sicherung von einzelnen Konfigurationsdateien (wegkopieren \u00fcber\u00a0SSH, z.B. mit putty und\u00a0Filezilla)<\/li>\n<li>Kopieren der gesamten SD Card in eine Datei (mit Win32Diskimager)<\/li>\n<\/ul>\n<p>Die aktuellen SD Cards sind recht gross (16-32GB) &#8211; die Dateien werden gleich gross. Ich habe mir deshalb ein Master-Abbild meiner Grundinstallation gemacht und diese auf ca. 3GB verkleinert. Grunds\u00e4tzlich gibt es dazu zwei Wege:<\/p>\n<ol>\n<li>Kopiere die SD Card in eine Datei und verkleinere die Partitionen <em>innerhalb der Datei<\/em><\/li>\n<li>verkleinere die Partitionen <em>direkt auf der SD Card<\/em> (vorher Sicherheitskopie machen)<\/li>\n<\/ol>\n<p>Der erste Weg ist hier\u00a0<a href=\"http:\/\/www.aoakley.com\/articles\/2015-10-09-resizing-sd-images.php\" target=\"_blank\">[3] <\/a>beschrieben und war mir zu aufwendig. Der zweite ist einfacher. Die Anleitung <a href=\"http:\/\/www.htpcguides.com\/easy-resize-and-back-up-raspberry-pi-sd-card-with-ubuntu\/\" target=\"_blank\">[4]<\/a> ist zwar lang und ausf\u00fchrlich, man kann sich aber einige Schritte der Vorbereitung\u00a0ersparen:<\/p>\n<ul>\n<li><a href=\"http:\/\/www.htpcguides.com\/install-ubuntu-virtual-machine-with-vmplayer-on-windows\/\" target=\"_blank\">Schritt 1: virtuelles Ubuntu erstellen<\/a><br \/>\nIch installierte ein Ubuntu 16.x mit VMware Workstation (irgend eine alte Version).<\/li>\n<li><a href=\"http:\/\/www.htpcguides.com\/install-ubuntu-vmware-tools-on-vmplayer\/\" target=\"_blank\">Schritt 2: VMWARE Tools installieren<br \/>\n<\/a>Dieses Gefrickel habe ich weggelassen. VMware schafft es seit fast 10 Jahren nicht, dies sauber hinzukriegen. Die Installation scheitert an einem vmci Modul, das aber gar nicht installiert ist&#8230;<\/li>\n<li><a href=\"http:\/\/www.htpcguides.com\/how-to-use-sd-card-reader-in-vmplayer-and-vmworkstation\/\" target=\"_blank\">Schritt 3: SD Card reader aktivieren<\/a><br \/>\nAuch das ist nicht n\u00f6tig. Unter VMware Workstation kann man die USB Ger\u00e4te (externe USB Platte, SD Card Reader&#8230;) einfach wahlweise am Host oder der virtuellen Maschine anh\u00e4ngen.<\/li>\n<\/ul>\n<p>Also\u00a0wird das jetzt\u00a0sehr\u00a0einfach:<\/p>\n<ol>\n<li>Kopie der SD Card erstellen, da diese direkt ver\u00e4ndert wird<\/li>\n<li>Ubuntu virtuell bereitmachen, mit VM Workstation sinngem\u00e4ss nach Schritt 1.<\/li>\n<li>SD Card einlegen und SD Card Reader in die VM durchreichen, sich mit <strong>sudo blkid<\/strong> die Partionen merken<br \/>\n<img loading=\"lazy\" class=\"alignnone wp-image-2409\" src=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2017\/01\/sd-shrink1.png\" alt=\"sd-shrink1\" width=\"656\" height=\"176\" srcset=\"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-content\/uploads\/2017\/01\/sd-shrink1.png 744w, http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-content\/uploads\/2017\/01\/sd-shrink1-300x81.png 300w\" sizes=\"(max-width: 656px) 100vw, 656px\" \/><\/li>\n<li>in Ubuntu mit <strong>gparted\u00a0<\/strong>umpartitionieren, sich die neue Gr\u00f6sse merken<br \/>\n<img loading=\"lazy\" class=\"alignnone wp-image-2410\" src=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2017\/01\/sd-shrink2.png\" alt=\"sd-shrink2\" width=\"661\" height=\"217\" srcset=\"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-content\/uploads\/2017\/01\/sd-shrink2.png 895w, http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-content\/uploads\/2017\/01\/sd-shrink2-300x99.png 300w, http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-content\/uploads\/2017\/01\/sd-shrink2-768x252.png 768w\" sizes=\"(max-width: 661px) 100vw, 661px\" \/><br \/>\n<img loading=\"lazy\" class=\"alignnone wp-image-2411\" src=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2017\/01\/sd-shrink3.png\" alt=\"sd-shrink3\" width=\"660\" height=\"450\" srcset=\"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-content\/uploads\/2017\/01\/sd-shrink3.png 777w, http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-content\/uploads\/2017\/01\/sd-shrink3-300x205.png 300w, http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-content\/uploads\/2017\/01\/sd-shrink3-768x524.png 768w\" sizes=\"(max-width: 660px) 100vw, 660px\" \/><br \/>\n<img loading=\"lazy\" class=\"alignnone wp-image-2412\" src=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2017\/01\/sd-shrink4.png\" alt=\"sd-shrink4\" width=\"661\" height=\"276\" srcset=\"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-content\/uploads\/2017\/01\/sd-shrink4.png 778w, http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-content\/uploads\/2017\/01\/sd-shrink4-300x125.png 300w, http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-content\/uploads\/2017\/01\/sd-shrink4-768x321.png 768w\" sizes=\"(max-width: 661px) 100vw, 661px\" \/><\/li>\n<li>in Ubuntu mit <strong>dd<\/strong> in eine .img Datei im Ubuntu schreiben (die Gr\u00f6sse hat man sich oben gemerkt, etwas Reserve dazu)<br \/>\n<img loading=\"lazy\" class=\"alignnone wp-image-2413\" src=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2017\/01\/sd-shrink5.png\" alt=\"sd-shrink5\" width=\"669\" height=\"152\" srcset=\"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-content\/uploads\/2017\/01\/sd-shrink5.png 709w, http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-content\/uploads\/2017\/01\/sd-shrink5-300x68.png 300w\" sizes=\"(max-width: 669px) 100vw, 669px\" \/><\/li>\n<li><strong>sudo sync<\/strong> in Ubuntu ausf\u00fchren und SD Card Reader von der VM abh\u00e4ngen<\/li>\n<li>Die\u00a0.img Datei auf den\u00a0Host Rechner bringen, z.B. via Netzwerk oder USB Stick transferieren<\/li>\n<li>auf dem Host Rechner\u00a0die .img Datei mit Win32Imager auf die neue Karte schreiben<\/li>\n<\/ol>\n<p>Damit hat man eine nur ca. 3GB grosse Datei erhalten. Im RPi kann \u00fcber das Menu (<strong>raspi-config<\/strong>) das Dateisystem auf die maximale Gr\u00f6sse expandiert werden. Man vergibt sich also nichts dabei.<\/p>\n<hr \/>\n<h5>Links<\/h5>\n<ol>\n<li><a href=\"http:\/\/wp.andreas.bieri.name\/myblog\/index.php\/2008\/04\/05\/workshop-virtualisierung-mit-vmware-server\/\" target=\"_blank\">Virtualisierung mit Vmware Server<\/a><\/li>\n<li><a href=\"https:\/\/thepihut.com\/blogs\/raspberry-pi-tutorials\/17789160-backing-up-and-restoring-your-raspberry-pis-sd-card\" target=\"_blank\">Backing up and Restoring your Raspberry Pi&#8217;s SD Card<\/a><\/li>\n<li><a href=\"http:\/\/www.aoakley.com\/articles\/2015-10-09-resizing-sd-images.php\" target=\"_blank\">Shrinking Raspberry Pi SD Card Images<\/a><\/li>\n<li><a href=\"http:\/\/www.htpcguides.com\/easy-resize-and-back-up-raspberry-pi-sd-card-with-ubuntu\/\" target=\"_blank\">http:\/\/www.htpcguides.com\/easy-resize-and-back-up-raspberry-pi-sd-card-with-ubuntu\/<\/a><\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die neueren Raspberry Pi Betriebssystem sind mittlerweile recht tolerant gegen\u00fcber &#8222;Stromausf\u00e4llen&#8220; geworden. Meine beiden RPi V3 mit Raspbian Jessie (Lite) haben\u00a0schon Dutzende\u00a0provizierte &#8222;Abst\u00fcrze&#8220; \u00fcberlebt. Trotzdem muss man ab und zu eine Sicherung anlagen. Daraus mache ich keine grosse Sache: Sicherung von einzelnen Konfigurationsdateien (wegkopieren \u00fcber\u00a0SSH, z.B. mit putty und\u00a0Filezilla) Kopieren der gesamten SD Card in [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[12],"tags":[94],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Raspberry Pi sichern, SD Card schrumpfen - Merkbar.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/52.29.166.97\/myblog\/2017\/01\/22\/raspberry-pi-sichern-sd-card-schrumpfen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Raspberry Pi sichern, SD Card schrumpfen - Merkbar.\" \/>\n<meta property=\"og:description\" content=\"Die neueren Raspberry Pi Betriebssystem sind mittlerweile recht tolerant gegen\u00fcber &#8222;Stromausf\u00e4llen&#8220; geworden. Meine beiden RPi V3 mit Raspbian Jessie (Lite) haben\u00a0schon Dutzende\u00a0provizierte &#8222;Abst\u00fcrze&#8220; \u00fcberlebt. Trotzdem muss man ab und zu eine Sicherung anlagen. Daraus mache ich keine grosse Sache: Sicherung von einzelnen Konfigurationsdateien (wegkopieren \u00fcber\u00a0SSH, z.B. mit putty und\u00a0Filezilla) Kopieren der gesamten SD Card in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/52.29.166.97\/myblog\/2017\/01\/22\/raspberry-pi-sichern-sd-card-schrumpfen\/\" \/>\n<meta property=\"og:site_name\" content=\"Merkbar.\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-22T09:28:02+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2017\/01\/sd-shrink1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"wp_blogadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#website\",\"url\":\"https:\/\/wp.andreas.bieri.name\/myblog\/\",\"name\":\"Merkbar.\",\"description\":\"IT, Elektronik und Mathematik\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wp.andreas.bieri.name\/myblog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/52.29.166.97\/myblog\/2017\/01\/22\/raspberry-pi-sichern-sd-card-schrumpfen\/#primaryimage\",\"inLanguage\":\"de\",\"url\":\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2017\/01\/sd-shrink1.png\",\"contentUrl\":\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2017\/01\/sd-shrink1.png\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/52.29.166.97\/myblog\/2017\/01\/22\/raspberry-pi-sichern-sd-card-schrumpfen\/#webpage\",\"url\":\"http:\/\/52.29.166.97\/myblog\/2017\/01\/22\/raspberry-pi-sichern-sd-card-schrumpfen\/\",\"name\":\"Raspberry Pi sichern, SD Card schrumpfen - Merkbar.\",\"isPartOf\":{\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/52.29.166.97\/myblog\/2017\/01\/22\/raspberry-pi-sichern-sd-card-schrumpfen\/#primaryimage\"},\"datePublished\":\"2017-01-22T09:28:02+00:00\",\"dateModified\":\"2017-01-22T09:28:02+00:00\",\"author\":{\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#\/schema\/person\/47691942dec3f2eb9d34bb8b5507870d\"},\"breadcrumb\":{\"@id\":\"http:\/\/52.29.166.97\/myblog\/2017\/01\/22\/raspberry-pi-sichern-sd-card-schrumpfen\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/52.29.166.97\/myblog\/2017\/01\/22\/raspberry-pi-sichern-sd-card-schrumpfen\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/52.29.166.97\/myblog\/2017\/01\/22\/raspberry-pi-sichern-sd-card-schrumpfen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/wp.andreas.bieri.name\/myblog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Raspberry Pi sichern, SD Card schrumpfen\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#\/schema\/person\/47691942dec3f2eb9d34bb8b5507870d\",\"name\":\"wp_blogadmin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#personlogo\",\"inLanguage\":\"de\",\"url\":\"http:\/\/1.gravatar.com\/avatar\/d0dc804558b03f640b22e497ec010c9a?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/1.gravatar.com\/avatar\/d0dc804558b03f640b22e497ec010c9a?s=96&d=mm&r=g\",\"caption\":\"wp_blogadmin\"},\"url\":\"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/author\/wp_blogadmin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Raspberry Pi sichern, SD Card schrumpfen - Merkbar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/52.29.166.97\/myblog\/2017\/01\/22\/raspberry-pi-sichern-sd-card-schrumpfen\/","og_locale":"de_DE","og_type":"article","og_title":"Raspberry Pi sichern, SD Card schrumpfen - Merkbar.","og_description":"Die neueren Raspberry Pi Betriebssystem sind mittlerweile recht tolerant gegen\u00fcber &#8222;Stromausf\u00e4llen&#8220; geworden. Meine beiden RPi V3 mit Raspbian Jessie (Lite) haben\u00a0schon Dutzende\u00a0provizierte &#8222;Abst\u00fcrze&#8220; \u00fcberlebt. Trotzdem muss man ab und zu eine Sicherung anlagen. Daraus mache ich keine grosse Sache: Sicherung von einzelnen Konfigurationsdateien (wegkopieren \u00fcber\u00a0SSH, z.B. mit putty und\u00a0Filezilla) Kopieren der gesamten SD Card in [&hellip;]","og_url":"http:\/\/52.29.166.97\/myblog\/2017\/01\/22\/raspberry-pi-sichern-sd-card-schrumpfen\/","og_site_name":"Merkbar.","article_published_time":"2017-01-22T09:28:02+00:00","og_image":[{"url":"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2017\/01\/sd-shrink1.png"}],"twitter_card":"summary","twitter_misc":{"Verfasst von":"wp_blogadmin","Gesch\u00e4tzte Lesezeit":"2 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#website","url":"https:\/\/wp.andreas.bieri.name\/myblog\/","name":"Merkbar.","description":"IT, Elektronik und Mathematik","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wp.andreas.bieri.name\/myblog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","@id":"http:\/\/52.29.166.97\/myblog\/2017\/01\/22\/raspberry-pi-sichern-sd-card-schrumpfen\/#primaryimage","inLanguage":"de","url":"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2017\/01\/sd-shrink1.png","contentUrl":"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2017\/01\/sd-shrink1.png"},{"@type":"WebPage","@id":"http:\/\/52.29.166.97\/myblog\/2017\/01\/22\/raspberry-pi-sichern-sd-card-schrumpfen\/#webpage","url":"http:\/\/52.29.166.97\/myblog\/2017\/01\/22\/raspberry-pi-sichern-sd-card-schrumpfen\/","name":"Raspberry Pi sichern, SD Card schrumpfen - Merkbar.","isPartOf":{"@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/52.29.166.97\/myblog\/2017\/01\/22\/raspberry-pi-sichern-sd-card-schrumpfen\/#primaryimage"},"datePublished":"2017-01-22T09:28:02+00:00","dateModified":"2017-01-22T09:28:02+00:00","author":{"@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#\/schema\/person\/47691942dec3f2eb9d34bb8b5507870d"},"breadcrumb":{"@id":"http:\/\/52.29.166.97\/myblog\/2017\/01\/22\/raspberry-pi-sichern-sd-card-schrumpfen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/52.29.166.97\/myblog\/2017\/01\/22\/raspberry-pi-sichern-sd-card-schrumpfen\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/52.29.166.97\/myblog\/2017\/01\/22\/raspberry-pi-sichern-sd-card-schrumpfen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/wp.andreas.bieri.name\/myblog\/"},{"@type":"ListItem","position":2,"name":"Raspberry Pi sichern, SD Card schrumpfen"}]},{"@type":"Person","@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#\/schema\/person\/47691942dec3f2eb9d34bb8b5507870d","name":"wp_blogadmin","image":{"@type":"ImageObject","@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#personlogo","inLanguage":"de","url":"http:\/\/1.gravatar.com\/avatar\/d0dc804558b03f640b22e497ec010c9a?s=96&d=mm&r=g","contentUrl":"http:\/\/1.gravatar.com\/avatar\/d0dc804558b03f640b22e497ec010c9a?s=96&d=mm&r=g","caption":"wp_blogadmin"},"url":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/author\/wp_blogadmin\/"}]}},"_links":{"self":[{"href":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-json\/wp\/v2\/posts\/2356"}],"collection":[{"href":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-json\/wp\/v2\/comments?post=2356"}],"version-history":[{"count":0,"href":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-json\/wp\/v2\/posts\/2356\/revisions"}],"wp:attachment":[{"href":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-json\/wp\/v2\/media?parent=2356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-json\/wp\/v2\/categories?post=2356"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/wp-json\/wp\/v2\/tags?post=2356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}